{"id":9512,"date":"2015-07-30T23:53:00","date_gmt":"2015-07-30T23:53:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=9512"},"modified":"2021-09-01T22:28:01","modified_gmt":"2021-09-01T22:28:01","slug":"5-idees-de-bike-tours-en-aquitaine","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/","title":{"rendered":"5 id\u00e9es de bike tours en Aquitaine"},"content":{"rendered":"<p>&#8220;<strong>1- La V\u00e9lodyss\u00e9e<\/strong><br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Du Cap-Ferret \u00e0 Arcachon (33)<\/p>\n<p>Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap ensuite sur le Bassin d&#8217;Arcachon, et la dune du Pilat. En tout, plus de 70 km de routes \u00e0 travers les stations baln\u00e9aires du littoral d&#8217;Aquitaine.<\/p>\n<p><strong>2- Circuit Vignes et Vergers en Duraquois<\/strong><br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Des rives du Dropt aux coteaux du P\u00e9rigord (47)<\/p>\n<p>D\u00e9couvrez entre deux coups de p\u00e9dale les richesses du patrimoine m\u00e9di\u00e9val et gastronomique du P\u00e9rigord. Ce circuit de 102 km serpente entre les vignobles AOC des C\u00f4tes de Duras, les pruniers d&#8217;Agen et les \u00e9levages d&#8217;oie&#8230; Une d\u00e9gustation s&#8217;impose, mais si vous pr\u00e9f\u00e9rez nourrir votre esprit, p\u00e9dalez jusqu&#8217;au Ch\u00e2teau de Duras, et impr\u00e9gnez-vous de ses 800 ans d&#8217;histoire.<\/p>\n<figure class='defer-image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/107000\/107833.jpg\" alt=\"La_V\u00e9lodyss\u00e9e\u00ae_\u00e0_Seignosse.jpg\" \/><figcaption>[La V\u00e9lodyss\u00e9e, Aquitaine &#8211; Cr\u00e9dit <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/2\/21\/La_V%C3%A9lodyss%C3%A9e%C2%AE_%C3%A0_Seignosse.jpg\/800px-La_V%C3%A9lodyss%C3%A9e%C2%AE_%C3%A0_Seignosse.jpg\">photo<\/a> : [Seignossetourism](<a href=\"https:\/\/commons.wikimedia.org\/w\/index.php?title=User:Seignossetourism&#038;action=edit&#038;redlink=1\">https:\/\/commons.wikimedia.org\/w\/index.php?title=User:Seignossetourism&#038;action=edit&#038;redlink=1<\/a> &#8220;User:Seignossetourism (page does not exist)&#8221;) sous licence <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/deed.en\">CC BY-SA 4.0<\/a>](<a href=\"https:\/\/commons.wikimedia.org\/w\/index.php?title=User:Seignossetourism&#038;action=edit&#038;redlink=1\">https:\/\/commons.wikimedia.org\/w\/index.php?title=User:Seignossetourism&#038;action=edit&#038;redlink=1<\/a> &#8220;User:Seignossetourism (page does not exist)&#8221;) sous licence <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/deed.en\">CC BY-SA 4.0<\/a>)<\/figcaption><\/figure>\n<p><strong>3- Boucle les Vignes du Seigneur<\/strong><br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>La Sauve (33)<\/p>\n<p>Cette petite boucle de 16 km vous emm\u00e8ne \u00e0 la d\u00e9couverte du vignoble de l&#8217;Entre-deux-Mers et de ses tr\u00e9sors d&#8217;art roman. Pr\u00e9voyez de nombreuses pauses pour visiter l&#8217;Abbaye de La Sauve Majeure, l&#8217;\u00e9glise Saint-Pierre, ou encore Notre Dame du Tout-Espoir. Apr\u00e8s avoir pleinement appr\u00e9ci\u00e9 toutes les finesses de l&#8217;architecture m\u00e9di\u00e9vale, les vignes vous appellent pour une petite d\u00e9gustation&#8230;<\/p>\n<p><strong>4- V\u00e9loroute de la vall\u00e9e du Lot<\/strong><br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>D&#8217;Aiguillon \u00e0 Cahors (47)<\/p>\n<p>Le nez au vent, p\u00e9dalant sur les petites routes balis\u00e9es, vous longez la rivi\u00e8re du Lot sur presque 160 km. Au fil de l&#8217;eau, vous fl\u00e2nez \u00e0 la d\u00e9couverte du patrimoine naturel et culturel de la r\u00e9gion. Les amateurs d&#8217;histoire m\u00e9di\u00e9vale peuvent s&#8217;accorder une halte au ch\u00e2teau fort de Bonaguil, un petit bijou du 15e si\u00e8cle.<\/p>\n<p><strong>5- Circuit des Cadets de Gascogne<\/strong><br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Casteljaloux (47)<\/p>\n<p>Enfourchez votre fid\u00e8le destrier et partez sur les traces des c\u00e9l\u00e8bres Cadets de Gascogne avec cette boucle de 87 km. Apr\u00e8s avoir p\u00e9dal\u00e9 dans la for\u00eat des Landes de Gascogne, vous attaquez sans fl\u00e9chir les coteaux du Marmandais. Une fois l\u00e0-haut, vous \u00eates r\u00e9compens\u00e9 par de sublimes panoramas sur la vall\u00e9e de la Garonne et les Landes&#8230;<\/p>\n<p><strong>O\u00f9 dormir en Aquitaine ?<\/strong> <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Consultez nos offres irr\u00e9sistibles d&#8217;<a href=\"https:\/\/www.expedia.fr\/Destinations-En-Aquitaine.d6049260.Destinations-hotels\"><strong>h\u00f4tels en Aquitaine<\/strong><\/a> et r\u00e9servez le v\u00f4tre sans plus tarder.<\/p>\n<p>Vous pouvez aussi d\u00e9couvrir notre guide &#8220;<a href=\"\/france\/aquitaine-limousin-poitou-charentes\/sejour-bien-etre-et-nature-en-aquitaine\/\">S\u00e9jour bien-\u00eatre et nature en Aquitaine<\/a>&#8221; avant votre d\u00e9part.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap&#8230;<\/p>\n","protected":false},"author":6,"featured_media":9514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[82,104,115,167,105,130,84],"tags":[69,59,9,13,20,30,8],"authors":[],"class_list":["post-9512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-city-break","category-fitness","category-nature","category-spring","category-sport","category-staycation","category-top-list","tag-city-break","tag-fitness","tag-nature","tag-sport","tag-spring","tag-staycation","tag-top-list","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia<\/title>\n<meta name=\"description\" content=\"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia\" \/>\n<meta property=\"og:description\" content=\"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-30T23:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/43000\/43196-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/\",\"name\":\"5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg\",\"datePublished\":\"2015-07-30T23:53:00+00:00\",\"dateModified\":\"2021-09-01T22:28:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City break\",\"item\":\"https:\/\/www.expedia.fr\/stories\/city-break\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5 id\u00e9es de bike tours en Aquitaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia","description":"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/","og_locale":"en_US","og_type":"article","og_title":"5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia","og_description":"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...","og_url":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/","og_site_name":"Expedia.fr","article_published_time":"2015-07-30T23:53:00+00:00","article_modified_time":"2021-09-01T22:28:01+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/43000\/43196-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/","url":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/","name":"5 id\u00e9es de bike tours en Aquitaine | Explore par Expedia","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg","datePublished":"2015-07-30T23:53:00+00:00","dateModified":"2021-09-01T22:28:01+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Du Cap-Ferret \u00e0 Arcachon (33)Pour votre bike tour en Aquitaine, empruntez la V\u00e9lodyss\u00e9e \u00e0 partir du Cap-Ferret, avant de longer la c\u00f4te du M\u00e9doc. Cap...","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/43196-share-image.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/5-idees-de-bike-tours-en-aquitaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"City break","item":"https:\/\/www.expedia.fr\/stories\/city-break\/"},{"@type":"ListItem","position":3,"name":"5 id\u00e9es de bike tours en Aquitaine"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/9512"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=9512"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/9512\/revisions"}],"predecessor-version":[{"id":18655,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/9512\/revisions\/18655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/9514"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=9512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=9512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=9512"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=9512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}