{"id":5174,"date":"2017-02-02T23:52:00","date_gmt":"2017-02-02T23:52:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=5174"},"modified":"2021-09-01T22:14:00","modified_gmt":"2021-09-01T22:14:00","slug":"ou-partir-en-decembre","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/","title":{"rendered":"O\u00f9 partir en d\u00e9cembre ?"},"content":{"rendered":"<p>&#8220;<\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115984.jpg\" alt=\"O\u00f9 partir en d\u00e9cembre ?\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### O\u00f9 partir en d\u00e9cembre ?<\/p>\n<p>Voyage au soleil, \u00e0 la neige ou de d\u00e9couverte culturelle : au mois de d\u00e9cembre, l&#8217;avantage c&#8217;est que vous pouvez programmer tous types de voyage ! Week-end en famille ou s\u00e9jour en amoureux, finissez l&#8217;ann\u00e9e en beaut\u00e9 sous le soleil des tropiques ou sous les flocons en Europe !<\/p>\n<p><\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115985.jpg\" alt=\"Bali, Indon\u00e9sie\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### Bali, Indon\u00e9sie<\/p>\n<p>Si vous ressentez le besoin d&#8217;une grosse dose de soleil pour vous remonter le moral et attaquer la nouvelle ann\u00e9e en pleine forme, Bali est la destination qu&#8217;il vous faut ! Difficile de r\u00e9sister \u00e0 la beaut\u00e9 naturelle de cette petite \u00eele de l&#8217;archipel indon\u00e9sien. Troquez le froid parisien contre le <em>farniente<\/em> sur des plages paradisiaques, la plong\u00e9e sous-marine, le surf, les excursions en for\u00eat, les rizi\u00e8res ou les temples, sans oublier l&#8217;ascension d&#8217;un des volcans ! Le Nouvel An \u00e0 Bali vous tente ? N&#8217;h\u00e9sitez pas&#8230; l&#8217;exp\u00e9rience ne peut que vous plaire !<\/p>\n<p><\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115986.jpg\" alt=\"Martinique, France\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### Martinique, France<\/p>\n<p>La Martinique est la destination soleil par excellence pour des vacances en famille, \u00e9t\u00e9 comme hiver ! Oubliez le stress du quotidien sur cette \u00eele de l&#8217;archipel des Antilles, situ\u00e9e dans les Cara\u00efbes. Climat tropical, eau transparente \u00e0 plus de 25 \u00b0C toute l&#8217;ann\u00e9e, plages paradisiaques : toutes les conditions sont r\u00e9unies pour vous d\u00e9tendre ! Pour les amateurs de sensations fortes, en route pour la plong\u00e9e sous-marine et des randonn\u00e9es \u00e0 l&#8217;int\u00e9rieur des terres. Les paysages alternent entre somptueuses for\u00eats tropicales, savanes, volcans, champs de canne \u00e0 sucre et villages pittoresques.<\/p>\n<p><\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115987.jpg\" alt=\"Prague, R\u00e9publique Tch\u00e8que\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### Prague, R\u00e9publique Tch\u00e8que<\/p>\n<p>Visiter Prague au mois de d\u00e9cembre, vous permet de d\u00e9couvrir l&#8217;une des plus belles villes d&#8217;Europe loin de l&#8217;affluence de l&#8217;\u00e9t\u00e9 ! Son incroyable richesse culturelle, historique et architecturale s&#8217;impr\u00e8gne, \u00e0 l&#8217;approche de No\u00ebl, d&#8217;une atmosph\u00e8re f\u00e9erique et chaleureuse. Parcourez le centre historique, ses quartiers et ses ruelles, visitez le ch\u00e2teau de Prague, la cath\u00e9drale Saint Guy, le pont Charles ou la place <em>Staro Namesti<\/em>. D\u00e8s la tomb\u00e9e de la nuit, rendez-vous dans une auberge ou un restaurant pour savourer une fameuse pinte et mettre \u00e0 l&#8217;\u00e9preuve la r\u00e9putation de la bi\u00e8re tch\u00e8que ! Ne manquez pas le march\u00e9 de No\u00ebl \u00e0 Prague et son ambiance magique et familiale.<\/p>\n<p><\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115988.jpg\" alt=\"Guanacaste, Costa Rica\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### Guanacaste, Costa Rica<\/p>\n<p>Situ\u00e9e au nord-ouest du Costa Rica sur la c\u00f4te pacifique, la province du Guanacaste offre une vari\u00e9t\u00e9 incroyable de lieux touristiques, entre plages, volcans et parcs nationaux. Au bord de l&#8217;eau comme \u00e0 l&#8217;int\u00e9rieur des terres, la beaut\u00e9 de la nature et la richesse de la biodiversit\u00e9 sont exceptionnelles. &#8221; Pura Vida &#8221; est l&#8217;expression populaire et positive la plus caract\u00e9ristique du Costa Rica, se traduisant par &#8221; vie pure &#8221; ou &#8221; vraie vie &#8220;. Toute une philosophie de vie !<\/p>\n<p><\/p>\n<figure class='' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/115000\/115989.jpg\" alt=\"Serre-Chevalier, France\" \/><figcaption>Photo : Shutterstock<\/p>\n<\/figcaption><\/figure>\n<p>### Serre-Chevalier, France<\/p>\n<p>Un s\u00e9jour en famille \u00e0 Serre-Chevalier en plein mois de d\u00e9cembre, \u00e7a vous tente ? Skiez d\u00e8s l&#8217;ouverture de la saison dans l&#8217;un des <strong>plus grands domaines d&#8217;Europe<\/strong> ! Cette station de sports d&#8217;hiver vous offre un cadre magnifique en plein c\u0153ur des Alpes du Sud et d&#8217;excellentes conditions de ski en neige naturelle d\u00e8s le d\u00e9but de l&#8217;hiver. Apr\u00e8s avoir d\u00e9val\u00e9 les pistes toute la journ\u00e9e, reposez-vous \u00e0 Brian\u00e7on ou dans l&#8217;un des villages typiques des Hautes-Alpes. D\u00e9paysement garanti !&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00f9 partir en d\u00e9cembre ?<\/p>\n","protected":false},"author":6,"featured_media":5180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[82,79,115,165,123],"tags":[17,69,9,10,144],"authors":[],"class_list":["post-5174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-city-break","category-vacation-ideas","category-nature","category-where-to-go-when","category-beach","tag-beach","tag-city-break","tag-nature","tag-vacation-ideas","tag-where-to-go-when","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O\u00f9 partir en d\u00e9cembre ? | Explore par Expedia<\/title>\n<meta name=\"description\" content=\"O\u00f9 partir en d\u00e9cembre ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 partir en d\u00e9cembre ?\" \/>\n<meta property=\"og:description\" content=\"O\u00f9 partir en d\u00e9cembre ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-02T23:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/24000\/24098-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/\",\"name\":\"O\u00f9 partir en d\u00e9cembre ? | Explore par Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg\",\"datePublished\":\"2017-02-02T23:52:00+00:00\",\"dateModified\":\"2021-09-01T22:14:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"O\u00f9 partir en d\u00e9cembre ?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg\",\"width\":1024,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City break\",\"item\":\"https:\/\/www.expedia.fr\/stories\/city-break\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O\u00f9 partir en d\u00e9cembre ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u00f9 partir en d\u00e9cembre ? | Explore par Expedia","description":"O\u00f9 partir en d\u00e9cembre ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/","og_locale":"en_US","og_type":"article","og_title":"O\u00f9 partir en d\u00e9cembre ?","og_description":"O\u00f9 partir en d\u00e9cembre ?","og_url":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/","og_site_name":"Expedia.fr","article_published_time":"2017-02-02T23:52:00+00:00","article_modified_time":"2021-09-01T22:14:00+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/24000\/24098-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/","url":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/","name":"O\u00f9 partir en d\u00e9cembre ? | Explore par Expedia","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg","datePublished":"2017-02-02T23:52:00+00:00","dateModified":"2021-09-01T22:14:00+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"O\u00f9 partir en d\u00e9cembre ?","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/24098-share-image.jpg","width":1024,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/ou-partir-en-decembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"City break","item":"https:\/\/www.expedia.fr\/stories\/city-break\/"},{"@type":"ListItem","position":3,"name":"O\u00f9 partir en d\u00e9cembre ?"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/5174"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=5174"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/5174\/revisions"}],"predecessor-version":[{"id":17863,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/5174\/revisions\/17863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/5180"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=5174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=5174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=5174"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=5174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}