{"id":4338,"date":"2013-07-08T05:48:00","date_gmt":"2013-07-08T05:48:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=4338"},"modified":"2021-09-01T22:10:14","modified_gmt":"2021-09-01T22:10:14","slug":"comment-ne-pas-sennuyer-a-la-plage","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/","title":{"rendered":"Comment ne pas s&#8217;ennuyer \u00e0 la plage?"},"content":{"rendered":"<p>&#8220;<a href=\"http:\/\/blogs-de-voyage.fr\/2013\/07\/08\/comment-ne-pas-sennuyer-a-la-plage\/grande-plage-biarritz\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/43000\/43155.jpg\" alt=\"Grande plage. Biarritz.\" \/><\/a><\/p>\n<p>Petite confession pour d\u00e9marrer la semaine: je ne suis pas une grande fan de la plage. Disons que ce n&#8217;est pas mon activit\u00e9 pr\u00e9f\u00e9r\u00e9e des vacances. Je pr\u00e9f\u00e8re largement faire une balade \u00e0 v\u00e9lo, ou bien faire le march\u00e9 ou encore faire une partie de tennis en plein cagnard. A la plage, j&#8217;ai l&#8217;impression de perdre mon temps et de griller mon capital solaire. Faire la cr\u00eape sur la plage pendant des heures histoire de revenir tann\u00e9e rien que pour \u00e9pater les copines du bureau, ce n&#8217;est pas trop mon truc et puis c&#8217;est super mauvais pour la peau. Et quitte \u00e0 r\u00e2ler, je ne suis pas une grande fan des grains de sable r\u00e9calcitrants qui collent \u00e0 la peau.<\/p>\n<p>Pour \u00e9viter de passer pour une totale asociale, je fais un effort et je vais \u00e0 la plage, comme tout le monde. Surtout pour faire plaisir aux autres.<\/p>\n<p>D\u00e9j\u00e0, on ne choisit pas l&#8217;heure la plus chaude de la journ\u00e9e pour y aller. En g\u00e9n\u00e9ral, c&#8217;est l\u00e0 qu&#8217;il y aura le plus de monde et que la distance entre votre serviette et celle des autres sera la plus r\u00e9duite. La plage oui, mais pas comme des sardines. Perso, j&#8217;adore y aller \u00e0 la fraiche pour avoir la plage pour moi toute seule ou bien vers 17h quand les gens commencent partir.<\/p>\n<p>On n&#8217;oublie pas les quelques artifices qui pourront rendre le moment plus agr\u00e9able.<\/p>\n<p>Les boules de p\u00e9tanques: rien de tel qu&#8217;une bonne partie de p\u00e9tanque entre amis sur la plage.<\/p>\n<p>Le pique-nique: \u00e0 ne pas oublier surtout s&#8217;il y a des enfants! Et puis si on va \u00e0 la plage en fin de journ\u00e9e, c&#8217;est sympa de pr\u00e9voir un petit ap\u00e9ro avec des choses \u00e0 grignoter.<\/p>\n<p><a href=\"http:\/\/blogs-de-voyage.fr\/2013\/07\/08\/comment-ne-pas-sennuyer-a-la-plage\/dunes-de-saint-jean-de-monts\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/43000\/43157.jpg\" alt=\"Dunes de Saint Jean de Monts\" \/><\/a><\/p>\n<p>Le kindle: qu&#8217;est-ce que j&#8217;ai pu bouquiner \u00e0 la plage! Depuis que j&#8217;ai un kindle, je trouve cela encore plus pratique car \u00e7a ne prend pratiquement pas de place dans le sac de plage.<\/p>\n<p>Ramasser des coquillages: une de mes activit\u00e9s pr\u00e9f\u00e9r\u00e9es \u00e0 la plage. On se munit d&#8217;un seau et on collecte les plus jolis coquillages de la plage ainsi que les galets polis par la mer. Une fois rentr\u00e9 \u00e0 la maison, on peut les mettre dans un joli bocal en verre pour d\u00e9corer, ou bien faire des colliers, construire un mobile, les peindre&#8230;<\/p>\n<p>Organiser un concours de sculpture sur sable. Trouver un th\u00e8me et c&#8217;est \u00e0 celui qui fera la plus belle r\u00e9alisation.<\/p>\n<p>Aller piquer une t\u00eate quand il fait fait trop chaud.<\/p>\n<p><strong>Et vous, que faites-vous \u00e0 la plage pour ne pas vous ennuyer?<\/strong>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment ne pas s&#8217;ennuyer \u00e0 la plage?<\/p>\n","protected":false},"author":6,"featured_media":4341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[10],"authors":[],"class_list":["post-4338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vacation-ideas","tag-vacation-ideas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment ne pas s&#039;ennuyer \u00e0 la plage?<\/title>\n<meta name=\"description\" content=\"Comment ne pas s&#039;ennuyer \u00e0 la plage?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment ne pas s&#039;ennuyer \u00e0 la plage?\" \/>\n<meta property=\"og:description\" content=\"Comment ne pas s&#039;ennuyer \u00e0 la plage?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-08T05:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/18000\/18805-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/\",\"name\":\"Comment ne pas s'ennuyer \u00e0 la plage?\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg\",\"datePublished\":\"2013-07-08T05:48:00+00:00\",\"dateModified\":\"2021-09-01T22:10:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Comment ne pas s'ennuyer \u00e0 la plage?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg\",\"width\":1024,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Id\u00e9es de vacances\",\"item\":\"https:\/\/www.expedia.fr\/stories\/vacation-ideas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment ne pas s&#8217;ennuyer \u00e0 la plage?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment ne pas s'ennuyer \u00e0 la plage?","description":"Comment ne pas s'ennuyer \u00e0 la plage?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/","og_locale":"en_US","og_type":"article","og_title":"Comment ne pas s'ennuyer \u00e0 la plage?","og_description":"Comment ne pas s'ennuyer \u00e0 la plage?","og_url":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/","og_site_name":"Expedia.fr","article_published_time":"2013-07-08T05:48:00+00:00","article_modified_time":"2021-09-01T22:10:14+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/18000\/18805-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/","url":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/","name":"Comment ne pas s'ennuyer \u00e0 la plage?","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg","datePublished":"2013-07-08T05:48:00+00:00","dateModified":"2021-09-01T22:10:14+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Comment ne pas s'ennuyer \u00e0 la plage?","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18805-share-image.jpg","width":1024,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/comment-ne-pas-sennuyer-a-la-plage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"Id\u00e9es de vacances","item":"https:\/\/www.expedia.fr\/stories\/vacation-ideas\/"},{"@type":"ListItem","position":3,"name":"Comment ne pas s&#8217;ennuyer \u00e0 la plage?"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/4338"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=4338"}],"version-history":[{"count":1,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/4338\/revisions"}],"predecessor-version":[{"id":14725,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/4338\/revisions\/14725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/4341"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=4338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=4338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=4338"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=4338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}