{"id":3719,"date":"2016-07-11T20:59:00","date_gmt":"2016-07-11T20:59:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=3719"},"modified":"2021-09-01T22:07:49","modified_gmt":"2021-09-01T22:07:49","slug":"le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/","title":{"rendered":"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l&#8217;h\u00f4tel aux robots !"},"content":{"rendered":"<p>&#8220;<em>Article r\u00e9dig\u00e9 par Mathilde Renversade &#8211; The Future of Travel &#8211; H\u00e9bergement<\/em><\/p>\n<p><em>Au Japon, un h\u00f4tel hors du commun vient d&#8217;ouvrir ses portes. Le<\/em> <a href=\"https:\/\/www.expedia.fr\/Nagasaki-Hotel-Huis-Ten-Bosch-Henn-Na-Hotel.h14864112.Description-Hotel?\"><em>Henn na Hotel<\/em><\/a><em>, L&#8217;Etrange H\u00f4tel en fran\u00e7ais, est le tout premier h\u00f4tel 100% robotique au monde. Bonne id\u00e9e commerciale ? Pas seulement. Dans un pays o\u00f9 la main d&#8217;\u0153uvre se fait de plus en plus rare et o\u00f9 les prix des h\u00f4tels sont \u00e9lev\u00e9s, les robots offrent une solution bon march\u00e9. Le Japon invente l&#8217;h\u00f4tel du futur et n&#8217;a pas fini de nous \u00e9tonner.<\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/41000\/41852.jpg\" alt=\"Henn na Hotel\" \/><\/p>\n<p><strong>Un dro**<\/strong>\u00ef<strong>**de pour vous servir<\/strong><\/p>\n<p>Le Henn na Hotel se situe dans le parc d&#8217;attractions de <a href=\"https:\/\/www.expedia.fr\/Huis-Ten-Bosch-Sasebo-Hotel.0-n6053920-0.Voyage-Guide-Filtre-Hotels\">Huis Ten Bosch<\/a> \u00e0 Sasebo, pr\u00e8s de Nagasaki. D\u00e8s le hall d&#8217;entr\u00e9e, le visiteur est projet\u00e9 dans le <a href=\"https:\/\/www.youtube.com\/watch?v=SnzzWGcdMqY\"><em>Cinqui\u00e8me \u00e9l\u00e9ment<\/em><\/a><em>.<\/em> Ici, les portiers sont des bras articul\u00e9s tout droit sortis des usines les plus high tech, et les r\u00e9ceptionnistes des dro\u00efdes aux allures bizarro\u00efdes.  <br \/>Nao, le c\u00e9l\u00e8bre petit robot, vous accueille dans toutes les langues et vous pr\u00e9sente l&#8217;h\u00f4tel ainsi que ses dr\u00f4les d&#8217;employ\u00e9s. Le responsable check in est un v\u00e9lociraptor. Apr\u00e8s quelques phrases de politesse convenues, il vous prie d&#8217;indiquer votre nom et de placer votre visage face \u00e0 une petite cam\u00e9ra sph\u00e9rique. Votre visage sera la cl\u00e9 de votre chambre gr\u00e2ce \u00e0 la reconnaissance faciale qui \u00e9quipe chaque porte.  <br \/>Un robot mobile charge vos bagages sur son dos. En route vers votre chambre \u00e0 l&#8217;allure d&#8217;un escargot et au son d&#8217;une musique disco que ses baffles lat\u00e9rales diffusent en continu. Au Henn na Hotel, il n&#8217;y a pas d&#8217;interrupteur. La lumi\u00e8re, la temp\u00e9rature de la pi\u00e8ce, le r\u00e9veil, tout se programme \u00e0 la voix, directement dans votre chambre aupr\u00e8s de votre assistant personnel : Chu-ri-chan.<\/p>\n<p>A l&#8217;ext\u00e9rieur de l&#8217;h\u00f4tel le spectacle continue. Commandez une collation sur une tablette, un drone vous la livre depuis les airs. Le g\u00e9rant de l&#8217;h\u00f4tel, Hideo Sawada, souhaite mettre en place prochainement des spectacles d&#8217;acrobaties de drones pour divertir ses clients.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/68000\/68759.jpg\" alt=\"Henn na Hotel\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/68000\/68760.jpg\" alt=\"Henn na Hotel\" \/><\/p>\n<p><strong>Les robots \u00e0 la conqu\u00eate du monde<\/strong><\/p>\n<p>Le Japon a toujours eu un don merveilleux pour m\u00ealer et maintenir un \u00e9quilibre entre majest\u00e9 de la tradition et surprise de la nouveaut\u00e9. <a href=\"https:\/\/www.expedia.fr\/Tokyo-Hotel-Shinjuku-Kuyakushomae-Capsule-Hotel.h3020494.Description-Hotel\">Capsules h\u00f4tels<\/a>, love h\u00f4tels et maintenant le robot h\u00f4tel, le march\u00e9 h\u00f4telier nippon ne manque pas d&#8217;imagination ! C&#8217;est parce que la concurrence y fait rage. Les prix y sont aussi \u00e9lev\u00e9s. Au Japon, il est difficile de trouver un h\u00e9bergement \u00e0 moins de 100 euros la nuit.<\/p>\n<p>Des nouveaux venus, comme le Henn na Hotel, cherchent \u00e0 bouleverser le march\u00e9 et \u00e0 tirer les prix vers le bas. Leur objectif : se positionner sur une offre low cost, sans pour autant sacrifier sur la qualit\u00e9 du service.<\/p>\n<p>La solution pour Hideo Sawada est claire : &#8221; embaucher &#8221; des robots et construire plus d&#8217;h\u00f4tels robotiques : &#8221; <em>Je pense que les h\u00f4tels \u00e0 bas prix vont se d\u00e9mocratiser comme pour les compagnies a\u00e9riennes low-cost. C&#8217;est le challenge que nous relevons (&#8230;) Dans le futur, nous esp\u00e9rons b\u00e2tir un millier d&#8217;h\u00f4tels similaires \u00e0 travers le monde.<\/em> &#8220;<\/p>\n<p>M\u00eame si le Henn na Hotel affiche un bon taux de remplissage, les avis des clients sont mitig\u00e9s : &#8221; <em>Au d\u00e9but c&#8217;est dr\u00f4le de voir tous ces robots, mais \u00e0 force je me suis un peu ennuy\u00e9e. Et puis on se sent seule car il n&#8217;y a pas de personnel.<\/em> &#8220;<\/p>\n<p>&#8221; <em>C&#8217;est bien les robots, mais ils ne nous comprennent pas toujours. Donc parfois c&#8217;est mieux d&#8217;avoir des humains.<\/em> &#8220;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/68000\/68761.jpg\" alt=\"Henn na Hotel\" \/>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !<\/p>\n","protected":false},"author":6,"featured_media":3723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,88],"tags":[54,10],"authors":[],"class_list":["post-3719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vacation-ideas","category-technology","tag-technology","tag-vacation-ideas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l&#039;h\u00f4tel aux robots ! | Explore par Expedia<\/title>\n<meta name=\"description\" content=\"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l&#039;h\u00f4tel aux robots !\" \/>\n<meta property=\"og:description\" content=\"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-11T20:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/18000\/18541-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/\",\"name\":\"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l'h\u00f4tel aux robots ! | Explore par Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg\",\"datePublished\":\"2016-07-11T20:59:00+00:00\",\"dateModified\":\"2021-09-01T22:07:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg\",\"width\":1024,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Id\u00e9es de vacances\",\"item\":\"https:\/\/www.expedia.fr\/stories\/vacation-ideas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l&#8217;h\u00f4tel aux robots !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l'h\u00f4tel aux robots ! | Explore par Expedia","description":"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/","og_locale":"en_US","og_type":"article","og_title":"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l'h\u00f4tel aux robots !","og_description":"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !","og_url":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/","og_site_name":"Expedia.fr","article_published_time":"2016-07-11T20:59:00+00:00","article_modified_time":"2021-09-01T22:07:49+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/18000\/18541-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/","url":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/","name":"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l'h\u00f4tel aux robots ! | Explore par Expedia","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg","datePublished":"2016-07-11T20:59:00+00:00","dateModified":"2021-09-01T22:07:49+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Vivez une exp\u2013\u03c0rience 100 % japonaise au Henn Na Hotel. Dans cet \u2013\u03c0tablissement de Nagasaki, du r\u2013\u03c0ceptionniste au groom, tous les employ\u2013\u03c0s\u201a\u00c4\u00b6 sont des robots !","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/18541-share-image.jpg","width":1024,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/le-receptionniste-est-un-velociraptor-bienvenue-dans-lhotel-aux-robots\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"Id\u00e9es de vacances","item":"https:\/\/www.expedia.fr\/stories\/vacation-ideas\/"},{"@type":"ListItem","position":3,"name":"Le r\u00e9ceptionniste est un v\u00e9lociraptor : bienvenue dans l&#8217;h\u00f4tel aux robots !"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/3719"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=3719"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/3719\/revisions"}],"predecessor-version":[{"id":17781,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/3719\/revisions\/17781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/3723"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=3719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=3719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=3719"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=3719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}