{"id":11589,"date":"2019-08-16T15:21:00","date_gmt":"2019-08-16T15:21:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=11589"},"modified":"2021-09-01T22:36:36","modified_gmt":"2021-09-01T22:36:36","slug":"partez-a-la-decouverte-damman-en-jordanie","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/","title":{"rendered":"Partez \u00e0 la d\u00e9couverte d&#8217;Amman, en Jordanie"},"content":{"rendered":"<p>&#8220;<strong>Amman compte parmi les villes les plus anciennes au monde<\/strong>. En raison de sa position strat\u00e9gique au c\u0153ur du Proche-Orient, cette ville a vu d\u00e9filer des civilisations diverses et vari\u00e9es. Et pourtant, Amman, capitale de la Jordanie, n&#8217;en reste pas moins <strong>la grande inconnue<\/strong>. Nous vous recommandons fortement de pr\u00e9voir un cr\u00e9neau de quelques jours dans votre feuille de route jordanienne pour d\u00e9couvrir cette m\u00e9tropole figurant parmi les villes les plus ouvertes et modernes du monde arabe.<\/p>\n<p>\u00c0 moins d&#8217;arriver en bateau de croisi\u00e8re, la plupart des voyageurs se rendent en Jordanie en avion et atterrissent \u00e0 l&#8217;a\u00e9roport d&#8217;Amman. C&#8217;est pourquoi, quelle que soit votre destination dans le royaume hach\u00e9mite, vous passerez n\u00e9cessairement par cette ville. Apr\u00e8s vous avoir conseill\u00e9 une petite halte dans la capitale de la Jordanie, voici quelques id\u00e9es de visites incontournables. Partons ensemble explorer chaque recoin de la ville et d\u00e9couvrir certaines de ses traditions, pour le moins curieuses !<\/p>\n<p>R\u00e9servez votre <a href=\"https:\/\/www.expedia.fr\/Jordanie.d90.Reservation-Sejours-Voyages\">voyage pour la Jordanie<\/a> et ne manquez aucun de ses tr\u00e9sors !<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184458.jpg\" alt=\"amman-4329305_1920.jpg?1569791688\" \/><\/p>\n<p>### Amman,nterre d&#8217;accueil<\/p>\n<p>En Jordanie, pr\u00e8s de la moiti\u00e9 de la populationndu pays vit dans la capitale. Le voyageur se retrouvera m\u00eal\u00e9 \u00e0 une diversit\u00e9 dencultures et rencontrera des habitants qui <strong>respirent le bonheur et langentillesse<\/strong>. De l\u00e0 lui vient peut-\u00eatre son surnom bien m\u00e9rit\u00e9 de <strong>&#8221; terrend&#8217;accueil &#8220;.<\/strong><\/p>\n<p>La Jordanie rec\u00e8le de magnifiques tr\u00e9sors. Lanrenomm\u00e9e de sites comme P\u00e9tra, la mer Morte ou le d\u00e9sert du Wadi Rum ancontribu\u00e9 \u00e0 laisser Amman dans l&#8217;ombre. Pourtant, consacrer quelques jours \u00e0nparcourir les principaux lieux d&#8217;une ville alliant <strong>l&#8217;ancien et le moderne<\/strong>npour dresser un tableau peu conformiste est une exp\u00e9rience incroyable.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/slapers\/48031678742\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184459.jpg\" alt=\"teatro_romano_amman.jpg?1565438956\" \/><\/a><\/p>\n<p>### Que voir \u00e0nAmman<\/p>\n<p>Amman est dot\u00e9e d&#8217;une histoire grandiose quinremonte jusqu&#8217;\u00e0 <strong>8 500 ans av. J.-C.<\/strong> On y a retrouv\u00e9 desnvestiges d&#8217;une implantation humaine locale datant du N\u00e9olithique. Depuis lors,nle devenir de la ville n&#8217;a cess\u00e9 de s&#8217;enrichir gr\u00e2ce aux influences d&#8217;autresnpeuples tels que les Romains ou les Ptol\u00e9m\u00e9es. Laissez-vous \u00e9merveiller par cenque cette ville a \u00e0 vous offrir !<\/p>\n<p>#### Le th\u00e9\u00e2tre romain<\/p>\n<p>Le th\u00e9\u00e2tre romain de la ville aux sept collinesna \u00e9t\u00e9 tr\u00e8s bien conserv\u00e9. Le billet d&#8217;entr\u00e9e pour le visiter donne \u00e9galementnacc\u00e8s \u00e0 deux mus\u00e9es et \u00e0 l&#8217;od\u00e9on. L&#8217;amphith\u00e9\u00e2tre en lui-m\u00eame estnparticuli\u00e8rement impressionnant. Avec sa capacit\u00e9 den6 000 spectateurs, le parcours de l&#8217;ar\u00e8ne aux gradins les plus hautsnn&#8217;est pas de tout repos. La vue depuis le haut en vaut toutefois la peine etnsera l&#8217;occasion d&#8217;admirer l&#8217;ampleur et la splendeur de ce th\u00e9\u00e2tre antique.<\/p>\n<p>#### La citadelle<\/p>\n<p>Depuis la colline \u00e0 proximit\u00e9, nous scrute <em>Jabalnal-Qala&#8217;a<\/em>, la citadelle. 7 000 ans d&#8217;histoire nous contemplent.nDes vestiges arch\u00e9ologiques de l&#8217;\u00e2ge du bronze et de l&#8217;\u00e2ge du fer se m\u00ealent auxntraces laiss\u00e9es par l&#8217;Empire romain et par les Omeyyades. C&#8217;est \u00e9galement, sansnaucun doute, le meilleur endroit pour profiter d&#8217;un panorama exceptionnel surnla ville.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/mayanais\/8501134787\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184460.jpg\" alt=\"ciudadela_amman.jpg?1565439658\" \/><\/a><\/p>\n<p>#### Le mus\u00e9e arch\u00e9ologique<\/p>\n<p>Tous deux ont \u00e9t\u00e9 am\u00e9nag\u00e9s \u00e0 l&#8217;int\u00e9rieur de la citadelle. Le mus\u00e9e arch\u00e9ologique abrite une collection d&#8217;une grande valeur et compte notamment des objets pr\u00e9historiques, des restes et objets issus de fouilles, qui datent du XVe si\u00e8cle.<\/p>\n<p>#### Le temple d&#8217;Hercule<\/p>\n<p>Le temple d&#8217;Hercule est un autre joyau h\u00e9rit\u00e9 de l&#8217;\u00e9poque romaine. Les colonnes et l&#8217;\u00e9norme main, vestige de ce qui fut une statue de 17 m\u00e8tres de haut, sont pour le moins impressionnantes.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/soham_pablo\/46640965161\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184461.jpg\" alt=\"templo_de_hercules_amman.jpg?1565439813\" \/><\/a><\/p>\n<p>### Que faire \u00e0nAmman<\/p>\n<p>Il est temps d&#8217;aller se promener et dend\u00e9ambuler dans les rues de la capitale de la Jordanie. Cette ville fa\u00e7onn\u00e9e parnles contrastes n&#8217;en est que plus attirante. Nous ne manquerons pas de vousnpr\u00e9senter certains lieux et quartiers incontournables.<\/p>\n<p>#### Promenadendans Rainbow Street<\/p>\n<p>Cette rue in\u00e9vitable se trouve dans la partienla plus haute de la ville, mais \u00e9galement dans l&#8217;un des quartiers les plusnmodernes et les plus luxueux d&#8217;Amman. Le quartier regorge de petites terrassesnet de caf\u00e9s, l&#8217;occasion de prendre un verre.<\/p>\n<p>Difficile en effet d&#8217;y \u00e9chapper, vu les ruesnpentues de <em>Rainbow Street<\/em>, tr\u00e8s bien bitum\u00e9es du reste.<\/p>\n<p>#### D\u00e9tour parn&#8221; Downtown &#8220;<\/p>\n<p><em>Downtown<\/em> n&#8217;est autre que le nom que l&#8217;on donne au centre-ville d&#8217;Amman. Ilns&#8217;agit du c\u0153ur de la vieille ville, centre bouillonnant et impr\u00e9gn\u00e9 d&#8217;unenatmosph\u00e8re quelque peu chaotique. Ce quartier vous donnera un aper\u00e7u dunv\u00e9ritable quotidien des Jordaniens.<\/p>\n<p>L&#8217;occasion de se perdre dans les ruelles, denvisiter souks et march\u00e9s, de partir en qu\u00eate d&#8217;objets d&#8217;artisanat et densouvenirs, de se prendre au jeu du marchandage et de profiter de la gentillessendes commer\u00e7ants qui vous inviteront \u00e0 prendre un th\u00e9 ou un caf\u00e9 avant d&#8217;entamernles n\u00e9gociations.<\/p>\n<p>#### \u00c0 land\u00e9couverte des graffitis<\/p>\n<p>Vous ne vous imaginiez certainement pas qu&#8217;un paysn\u00e0 majorit\u00e9 musulmane puisse abriter une telle profusion de street art. C&#8217;estnpourtant le cas. Ces fa\u00e7ades et ces murs \u00e9clatants de couleurs sont un d\u00e9licenpour les yeux. Vous croiserez de nombreux graffitis en vous promenant dans _Downtonw_nou en vous dirigeant vers les collines.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/poisonbabyfood\/3166638291\/\"><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184462.jpg\" alt=\"mercado_amman.jpg?1565440461\" \/><\/a><\/p>\n<p>### Shoppingndans la capitale de la Jordanie<\/p>\n<p>Amman est \u00e9galement dot\u00e9e de multiplesnboutiques o\u00f9 vous pourrez faire vos emplettes. La ville comprend un quartiernmarchand plus traditionnel accol\u00e9 \u00e0 des zones plus modernes d&#8217;allure occidentale.<\/p>\n<p>#### Len&#8221; souk de l&#8217;or &#8220;<\/p>\n<p>Vous devez absolument vous rendre dans cettenrue dans laquelle se concentrent quantit\u00e9 de boutiques sp\u00e9cialis\u00e9es dans lanvente d&#8217;objets en or. Les prix s&#8217;av\u00e8rent plus int\u00e9ressants qu&#8217;en Europe et lenchoix, qu&#8217;il s&#8217;agisse des mod\u00e8les et du design des objets, est gigantesque.<\/p>\n<p>#### Les souks<\/p>\n<p>Oubliez l&#8217;id\u00e9e que l&#8217;on se faitntraditionnellement du souk arabe. Ici, point d&#8217;entrelacs de ruelles couvertes.nLa conception s&#8217;apparente plus aux march\u00e9s tels qu&#8217;on les trouve en Europe. Ennrevanche, vous trouverez de tout : de l&#8217;artisanat traditionnel, des tapis,ndes p\u00e2tisseries populaires, de quoi se restaurer, des \u00e9pices, etc.nPr\u00e9parez-vous \u00e0 n\u00e9gocier !<\/p>\n<p>#### Al sweifieh<\/p>\n<p>Il s&#8217;agit du quartier branch\u00e9 de la ville. Desnboutiques de pr\u00eat-\u00e0-porter et des enseignes internationales s&#8217;y sontninstall\u00e9es. C&#8217;est l&#8217;endroit id\u00e9al si vous cherchez des objets de luxe.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184463.jpg\" alt=\"Knafeh.jpeg?1565441101\" \/><\/p>\n<p>### Senrestaurer et prendre un verre<\/p>\n<p>Comme tout pays arabe, la gastronomie y estnexcellente. Le choix ne manque pas : vous pourrez alterner petits platsncuisin\u00e9s par les marchands ambulants et mets gastronomiques recherch\u00e9s dans desnrestaurants plus chics. Quoi qu&#8217;il en soit, vous ne pourrez \u00e9chapper \u00e0ncertaines sp\u00e9cialit\u00e9s.<\/p>\n<p>&#8211; <strong><em>Le Mansaf<\/em>**<\/strong>.<strong> Ce plat d\u00e9licieuxn est la sp\u00e9cialit\u00e9 culinaire la plus typique de Jordanie. Vous nen regretterez pas d&#8217;avoir go\u00fbt\u00e9 \u00e0 ce riz \u00e9pic\u00e9 au safran accompagn\u00e9 den c\u00f4telettes d&#8217;agneau baignant dans du <em>jameed<\/em>, une sorte de yaourt.<br \/>&#8211; <\/strong>P\u00e2tisseries arabes.<strong> Exit <em>brownies<\/em> et <em>pancakes<\/em>,n la p\u00e2tisserie arabe est le fruit d&#8217;une longue tradition. D\u00e9gustez cesn plaisirs sucr\u00e9s que sont <em>el faisaliah, el ma&#8217;moul ou el bazarek<\/em> etn faites confiance aux sensations que suscite ce qui est propos\u00e9 enn vitrines.<br \/>&#8211; <\/strong><em>Le Knafeh<\/em><strong>. Il s&#8217;agit d&#8217;un g\u00e2teau traditionnel. Faufilez-vous dans l&#8217;unen des p\u00e2tisseries au centre d&#8217;Amman et demandez l&#8217;une de ces bouch\u00e9es qui sen pr\u00e9sentent sous forme de fils. Elles sont enrob\u00e9es d&#8217;un d\u00e9licieux fromagen frais et d&#8217;une cro\u00fbte feuillet\u00e9e orang\u00e9e. La touche finale vient de sonn enrobage \u00e0 base d&#8217;un sirop de sucre.<br \/>&#8211; <\/strong>Visite au Wild Jordan Caf\u00e9.<strong> Ce caf\u00e9, en dehors des vues spectaculairesn qu&#8217;il offre, appartient \u00e0 la Soci\u00e9t\u00e9 royale pour la conservation de lan nature. Il propose une nourriture saine \u00e0 base de produits r\u00e9colt\u00e9s dans lesn plaines mara\u00eech\u00e8res des r\u00e9serves naturelles. Les revenus engendr\u00e9s sontn destin\u00e9s \u00e0 la conservation de la biodiversit\u00e9 de la Jordanie.<br \/>&#8211; <\/strong>Le falafel le plus ancien d&#8217;Amman<strong>. Rendez-vous chez _<u>Al-Quds<\/u>_n pour d\u00e9guster un falafel anthologique. Ce lieu est le restaurant den falafels le plus ancien de la capitale ; il se trouve \u00e0 <em>Jabaln Amman<\/em>. Un incontournable.<br \/>&#8211; <\/strong><em>Salah Ad-Dine.<\/em><strong> Testons un autre lieu qui compte parmin les plus anciens d&#8217;Amman. Il s&#8217;agit cette fois d&#8217;une boulangerie qui vousn proposera de pr\u00e9parer votre propre <em>ka&#8217;ek<\/em> frais.<br \/>&#8211; <\/strong>Jus de canne \u00e0 sucre.<strong> C&#8217;est une boisson typique de ce lieu.n Optez pour l&#8217;un des nombreux kiosques ou \u00e9tals qui extraient le jus den canne devant vous.<br \/>&#8211; <\/strong>Caf\u00e9 jordanien et <em>shisha<\/em>.<strong> Accordez-vous une pause autour d&#8217;un caf\u00e9,n exquis, \u00e0 la jordanienne, agr\u00e9ment\u00e9 de graines de cardamome. L&#8217;occasion den se relaxer en fumant la <em>shisha<\/em> selon le parfum que vous choisirez.n Les nombreux caf\u00e9s en terrasse que vous trouverez partout dans la villen vous le proposeront.<\/p>\n<p>Il ne s&#8217;agit bien entendu que de quelquesnsuggestions pour vous permettre de profiter au mieux de votre s\u00e9jour \u00e0 Amman.nVisiter l&#8217;une des villes les plus anciennes au monde va bien au-del\u00e0. En moinsnde temps qu&#8217;il ne faut pour le dire, vous aurez vous-m\u00eame d\u00e9nich\u00e9 tout un \u00e9ventailnde choses \u00e0 faire et de lieux surprenants \u00e0 d\u00e9couvrir qui feront de votrens\u00e9jour dans la capitale de la Jordanie une exp\u00e9rience inoubliable. \u00c0 vous denjouer et bon voyage !<\/p>\n<p><\/strong>Vous avez aim\u00e9 ce guide ? Alors vous allez adorer d\u00e9couvrir la Jordanie sous toutes les coutures en consultant nos guides de voyage :**<\/p>\n<p>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/road-trip-en-jordanie-en-10-etapes-incontournables\">Road trip en Jordanie en 10 \u00e9tapes incontournables<\/a><br \/>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/a-voir-et-a-faire-en-jordanie-les-incontournables\">\u00c0 voir et \u00e0 faire en Jordanie : les incontournables<\/a><br \/>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/10-incontournables-de-la-cite-de-petra-en-jordanie\">10 incontournables de la cit\u00e9 de Petra en Jordanie<\/a><br \/>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/desert-de-wadi-rum-en-jordanie-10-sites-a-visiter\">D\u00e9sert de Wadi Rum en Jordanie : 10 sites \u00e0 visiter<\/a><br \/>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/aqaba-en-jordanie-plage-mer-et-histoire\">Aqaba en Jordanie : plage, mer et histoire<\/a><br \/>&#8211; <a href=\"https:\/\/www.expedia.fr\/explore\/tout-savoir-sur-la-mer-morte-en-jordanie\">Tout savoir sur la Mer Morte en Jordanie<\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condens\u00e9 des incontournables d&#8217;Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique<\/p>\n","protected":false},"author":6,"featured_media":11591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[129,175,120,79,125,163],"tags":[16,38,140,112,110,10],"authors":[],"class_list":["post-11589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-best-of","category-day-trips","category-history","category-vacation-ideas","category-landmarks","category-hidden-gem","tag-best-of","tag-day-trips","tag-hidden-gem","tag-history","tag-landmarks","tag-vacation-ideas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Jordanie autrement : Amman, cette inconnue | Explore par Expedia<\/title>\n<meta name=\"description\" content=\"Condens\u00e9 des incontournables d&#039;Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partez \u00e0 la d\u00e9couverte d&#039;Amman, en Jordanie\" \/>\n<meta property=\"og:description\" content=\"Condens\u00e9 des incontournables d&#039;Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-16T15:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184457-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/\",\"name\":\"La Jordanie autrement : Amman, cette inconnue | Explore par Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg\",\"datePublished\":\"2019-08-16T15:21:00+00:00\",\"dateModified\":\"2021-09-01T22:36:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Condens\u00e9 des incontournables d'Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Best of\",\"item\":\"https:\/\/www.expedia.fr\/stories\/best-of\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Partez \u00e0 la d\u00e9couverte d&#8217;Amman, en Jordanie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Jordanie autrement : Amman, cette inconnue | Explore par Expedia","description":"Condens\u00e9 des incontournables d'Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/","og_locale":"en_US","og_type":"article","og_title":"Partez \u00e0 la d\u00e9couverte d'Amman, en Jordanie","og_description":"Condens\u00e9 des incontournables d'Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique","og_url":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/","og_site_name":"Expedia.fr","article_published_time":"2019-08-16T15:21:00+00:00","article_modified_time":"2021-09-01T22:36:36+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/184000\/184457-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/","url":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/","name":"La Jordanie autrement : Amman, cette inconnue | Explore par Expedia","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg","datePublished":"2019-08-16T15:21:00+00:00","dateModified":"2021-09-01T22:36:36+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Condens\u00e9 des incontournables d'Amman en Jordanie : visites culturelles, d\u00e9couverte de la ville, shopping et culture gastronomique","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/07\/184457-share-image.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/partez-a-la-decouverte-damman-en-jordanie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"Best of","item":"https:\/\/www.expedia.fr\/stories\/best-of\/"},{"@type":"ListItem","position":3,"name":"Partez \u00e0 la d\u00e9couverte d&#8217;Amman, en Jordanie"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/11589"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=11589"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/11589\/revisions"}],"predecessor-version":[{"id":19119,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/11589\/revisions\/19119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/11591"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=11589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=11589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=11589"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=11589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}