{"id":10742,"date":"2018-12-14T17:44:00","date_gmt":"2018-12-14T17:44:00","guid":{"rendered":"https:\/\/expedia.blog.fr.sandwave.dev\/stories\/?p=10742"},"modified":"2021-09-01T22:33:18","modified_gmt":"2021-09-01T22:33:18","slug":"10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original","status":"publish","type":"post","link":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/","title":{"rendered":"10 id\u00e9es pour un enterrement de vie de jeune fille original"},"content":{"rendered":"<p>&#8220;Votre meilleure amie se marie et vous r\u00eavez pour elle d&#8217;un enterrement de vie de jeune fille \u00e0 son image : hors du commun ? D\u00e9couvrez nos <strong>10 id\u00e9es pour un EVJF original<\/strong> qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.<\/p>\n<p>1- Cabaret burlesque \u00e0 Paris<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179444.jpg\" alt=\"Burlesque_CC0.jpg?1544809749\" \/><\/p>\n<p>\u00c0 Paris, c&#8217;est le cabaret burlesque qui est en vogue depuis une dizaine d&#8217;ann\u00e9es. Il met en sc\u00e8ne des spectacles comiques et coquins sur un mode d\u00e9cal\u00e9 et irr\u00e9v\u00e9rencieux&#8230; tr\u00e8s loin des clich\u00e9s entourant le strip-tease. Entre copines, vous pourrez boire un verre en assistant \u00e0 un spectacle, mais aussi prendre un cours d&#8217;effeuillage fa\u00e7on &#8221; pin up des ann\u00e9es 50 &#8220;. Fous rires garantis !<\/p>\n<p>2- D\u00e9couverte du patrimoine architectural de Riga<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179445.jpg\" alt=\"Riga_EVJF_CC0.jpg?1544809864\" \/><\/p>\n<p>La future mari\u00e9e est f\u00e9rue d&#8217;art et de culture ? Emmenez-la \u00e0 Riga ! La <u>[capitale lettonne](<a href=\"https:\/\/www.expedia.fr\/Riga-Hotel.d6056778.Voyage-Guide-Hotels\">https:\/\/www.expedia.fr\/Riga-Hotel.d6056778.Voyage-Guide-Hotels<\/a> &#8220;hotel sejour riga&#8221;)<\/u> vaut le d\u00e9tour : fl\u00e2nez dans la vieille ville class\u00e9e au patrimoine mondial de l&#8217;UNESCO, admirez les b\u00e2timents &#8221; Art nouveau &#8221; dans le quartier de Centrs&#8230; Vous pourrez aussi profiter des mus\u00e9es de la ville et, le soir venu, des nombreux bars \u00e0 bi\u00e8re !<\/p>\n<p>3- Spa et massage \u00e0 Marrakech<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179446.jpg\" alt=\"Massage_Marrakech_EVJF_CC0.jpg?1544810067\" \/><\/p>\n<p>Marrakech est la destination id\u00e9ale si vous souhaitez passer avec votre amie un moment de relaxation totalement d\u00e9paysant. Testez le traditionnel hammam : d\u00e9tendez-vous dans les bains de vapeur, poursuivez avec un gommage et terminez avec un d\u00e9licieux massage \u00e0 l&#8217;huile d&#8217;argan. Vous pouvez \u00e9galement offrir \u00e0 la future mari\u00e9e un soin du visage ou une s\u00e9ance de manucure.<\/p>\n<p>4- S\u00e9jour gourmand \u00e0 Rome<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179447.jpg\" alt=\"Restaurant_Italie_EVJF_CC0.jpg?1544810260\" \/><\/p>\n<p>Si la future mari\u00e9e est une vraie gourmande, un EVJF sur le th\u00e8me de la [gastronomie italienne](<a href=\"http:\/\/expedia.fr\/explore\/10-specialites-culinaires-incontournables-de-litalie\">http:\/\/expedia.fr\/explore\/10-specialites-culinaires-incontournables-de-litalie<\/a> &#8220;gastronomie italienne&#8221;) ne pourra que l&#8217;enchanter. Dans le cadre romantique de la capitale romaine, \u00e0 vous les pizzas, bruschettas et autres antipasti ! Apr\u00e8s une visite dans un <em>mercato<\/em> pour d\u00e9couvrir les produits du terroir, assistez \u00e0 un cours de pr\u00e9paration de p\u00e2tes et prenez un bon repas dans une <em>trattoria<\/em>, restaurant italien traditionnel et familial.<\/p>\n<p>5- Chasse au tr\u00e9sor dans Barcelone<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179448.jpg\" alt=\"Placa_Reial_Barcelone_CC0.jpg?1544810495\" \/><\/p>\n<p>Barcelone est une destination tr\u00e8s pris\u00e9e pour les enterrements de vie de c\u00e9libataire. Pour y vivre une exp\u00e9rience originale, choisissez de (re) visiter la capitale catalane diff\u00e9remment. Optez pour une chasse au tr\u00e9sor ou une ballade en Segway dans les ruelles pleines de charme du centre-ville.<\/p>\n<p>6- Randonn\u00e9e dans les Highlands \u00e9cossais<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179449.jpg\" alt=\"Ecosse_EVJF_CC0.jpg?1544810569\" \/><\/p>\n<p>Amoureuses de nature et de paysages sauvages, la r\u00e9gion des Highlands en \u00c9cosse est faite pour vous ! Au programme : randonn\u00e9e sur le West Highlands Way, visite de l&#8217;\u00eele de Skye sans oublier l&#8217;incontournable lac du Loch Ness. C\u00f4t\u00e9 h\u00e9bergement, vous pouvez camper dans un paysage \u00e0 couper le souffle, ou pr\u00e9f\u00e9rer un <u><a href=\"https:\/\/www.expedia.fr\/Hotel-Search?destination=Highlands+%C3%A9cossais,+%C3%89cosse,+Royaume-Uni&#038;latLong=57.120000,-4.710000%C2%AEionId=6051150&#038;startDate=&#038;endDate=&#038;rooms=1&#038;_xpid=11905%7C1&#038;adults=2\">h\u00f4tel<\/a><\/u><u> <\/u>au charme pittoresque.<\/p>\n<p>7- Street art et musique alternative \u00e0 Berlin<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179450.jpg\" alt=\"Berlin_Street_Art_CC0_EVJF.jpg?1544810688\" \/><\/p>\n<p>Berlin est une capitale bouillonnante bien connue pour sa <u><a href=\"http:\/\/expedia.fr\/explore\/berlin-capitale-underground-et-alternative\">culture underground<\/a><\/u>. Pour un EVJF hors des sentiers battus, partez \u00e0 la d\u00e9couverte du street art dans le quartier de Kreuzberg, et sur l&#8217;East side Gallery, o\u00f9 des artistes ont peint les vestiges du mur de Berlin. Et pour une soir\u00e9e inoubliable, direction les bars pour un concert rock ou les clubs pour les amatrices de musique \u00e9lectronique !<\/p>\n<p>8- Bordeaux au fil de la Garonne<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179451.jpg\" alt=\"Toulouse_1_CC0.jpg?1544810790\" \/><\/p>\n<p>Vous recherchez une activit\u00e9 ludique et insolite \u00e0 Bordeaux ? Pas d&#8217;h\u00e9sitation ! Proposez \u00e0 la future mari\u00e9e une excursion en cano\u00eb sur la Garonne. Une occasion de d\u00e9couvrir les quais bordelais, le patrimoine architectural et l&#8217;histoire de la ville, la faune et la flore du bord de Garonne, le tout sous un tout autre jour.<\/p>\n<p>9- Des sensations fortes dans les \u00eeles Canaries<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179452.jpg\" alt=\"Surf_EVJF_Canaries_CC0.jpg?1544811041\" \/><\/p>\n<p>Les \u00eeles Canaries sont une destination privil\u00e9gi\u00e9e qui allie farniente et pleine nature. Pour celles qui n&#8217;ont pas froid aux yeux, faites-y votre bapt\u00eame en parapente et survolez les splendides c\u00f4tes de [l<u>&#8216;\u00eele de Tenerife<\/u>](<a href=\"https:\/\/www.expedia.fr\/Tenerife-Hotel.d6047194.Voyage-Guide-Hotels\">https:\/\/www.expedia.fr\/Tenerife-Hotel.d6047194.Voyage-Guide-Hotels<\/a> &#8220;sejour hotel ile tenerife&#8221;). Les amatrices de sports nautiques y trouveront \u00e9galement leur compte : jet-ski, surf ou encore parachute ascensionnel, vous aurez l&#8217;embarras du choix !<\/p>\n<p>10- Tea time et tourn\u00e9e des bars \u00e0 Londres<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/179000\/179453.jpg\" alt=\"Bar_Londres_EVJF_CC0.jpg?1544811268\" \/><\/p>\n<p>Londres, une ville fashion et girly id\u00e9ale pour un EVJF ! Pour vous mettre \u00e0 l&#8217;heure anglaise, rien de mieux que de prendre l&#8217;<em>afternoon tea.<\/em> H\u00f4tels chics et raffin\u00e9s, classiques salons de th\u00e9, sans oublier l&#8217;insolite bus rouge dans lequel vous pourrez prendre le th\u00e9 tout en d\u00e9couvrant le centre londonien : il y en a pour tous les go\u00fbts. Encha\u00eenez avec une soir\u00e9e dans les clubs de Soho ou dans les bars et salles de concert de Camden Town.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.<\/p>\n","protected":false},"author":6,"featured_media":10745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[82,98,111,79,83,84],"tags":[69,36,28,66,8,10],"authors":[],"class_list":["post-10742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-city-break","category-party","category-food-wine","category-vacation-ideas","category-shopping","category-top-list","tag-city-break","tag-food-wine","tag-party","tag-shopping","tag-top-list","tag-vacation-ideas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 10 destinations pour un EVJF original | Explore par Expedia<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 id\u00e9es pour un enterrement de vie de jeune fille original\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.fr\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T17:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/145000\/145134-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/\",\"url\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/\",\"name\":\"Top 10 destinations pour un EVJF original | Explore par Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg\",\"datePublished\":\"2018-12-14T17:44:00+00:00\",\"dateModified\":\"2021-09-01T22:33:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage\",\"url\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.fr\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City break\",\"item\":\"https:\/\/www.expedia.fr\/stories\/city-break\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 id\u00e9es pour un enterrement de vie de jeune fille original\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#website\",\"url\":\"https:\/\/www.expedia.fr\/stories\/\",\"name\":\"Expedia.fr\",\"description\":\"Votre voyage commence ici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 10 destinations pour un EVJF original | Explore par Expedia","description":"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/","og_locale":"en_US","og_type":"article","og_title":"10 id\u00e9es pour un enterrement de vie de jeune fille original","og_description":"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.","og_url":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/","og_site_name":"Expedia.fr","article_published_time":"2018-12-14T17:44:00+00:00","article_modified_time":"2021-09-01T22:33:18+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/145000\/145134-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/","url":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/","name":"Top 10 destinations pour un EVJF original | Explore par Expedia","isPartOf":{"@id":"https:\/\/www.expedia.fr\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg","datePublished":"2018-12-14T17:44:00+00:00","dateModified":"2021-09-01T22:33:18+00:00","author":{"@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"D\u00e9couvrez nos 10 id\u00e9es pour un EVJF original qui allient destinations d\u00e9paysantes et exp\u00e9riences inoubliables.","breadcrumb":{"@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#primaryimage","url":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg","contentUrl":"https:\/\/www.expedia.fr\/stories\/wp-content\/uploads\/2021\/06\/145134-share-image.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.fr\/stories\/10-idees-pour-un-enterrement-de-vie-de-jeune-fille-original\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.fr\/stories\/"},{"@type":"ListItem","position":2,"name":"City break","item":"https:\/\/www.expedia.fr\/stories\/city-break\/"},{"@type":"ListItem","position":3,"name":"10 id\u00e9es pour un enterrement de vie de jeune fille original"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.fr\/stories\/#website","url":"https:\/\/www.expedia.fr\/stories\/","name":"Expedia.fr","description":"Votre voyage commence ici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.fr\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.fr\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.fr\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/10742"}],"collection":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/comments?post=10742"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/10742\/revisions"}],"predecessor-version":[{"id":18939,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/posts\/10742\/revisions\/18939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media\/10745"}],"wp:attachment":[{"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/media?parent=10742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/categories?post=10742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/tags?post=10742"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.fr\/stories\/wp-json\/wp\/v2\/authors?post=10742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}